{"id":3898,"date":"2020-02-04T19:12:31","date_gmt":"2020-02-04T10:12:31","guid":{"rendered":"https:\/\/manbo-p.com\/?page_id=3898"},"modified":"2020-02-04T19:16:27","modified_gmt":"2020-02-04T10:16:27","slug":"contact","status":"publish","type":"page","link":"https:\/\/manbo-p.com\/en\/contact","title":{"rendered":"CONTACT"},"content":{"rendered":"<p>[vc_row][vc_column]<div id=\"la_divider6a0424514843e\" class=\"js-el la-divider la-unit-responsive\" data-la_component=\"UnitResponsive\"  data-el_target='#la_divider6a0424514843e'  data-el_media_sizes='{&quot;padding-top&quot;:&quot;lg:60px;&quot;}' ><\/div>\n[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f3897-o1\" lang=\"ja\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/3898#wpcf7-f3897-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3897\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ja\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3897-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> your name*<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> your e-mail*<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> For who?*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"subject-to\"><select name=\"subject-to\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"For manbo-p\">For manbo-p<\/option><option value=\"For Yoh Takahashi\">For Yoh Takahashi<\/option><option value=\"For Tsukasa Ryugu\">For Tsukasa Ryugu<\/option><\/select><\/span> <\/label><\/p>\n<p><label> subject<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> message*<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"submit\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_locale":"en_US","_original_post":"3894"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/pages\/3898"}],"collection":[{"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/comments?post=3898"}],"version-history":[{"count":1,"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/pages\/3898\/revisions"}],"predecessor-version":[{"id":3899,"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/pages\/3898\/revisions\/3899"}],"wp:attachment":[{"href":"https:\/\/manbo-p.com\/wp-json\/wp\/v2\/media?parent=3898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}